{"id":1078,"date":"2016-05-12T16:02:00","date_gmt":"2016-05-12T14:02:00","guid":{"rendered":"https:\/\/2016.bilbao.wordcamp.org\/?p=1078"},"modified":"2016-05-20T14:10:36","modified_gmt":"2016-05-20T12:10:36","slug":"siteground-patrocinador-oro-wordcamp-bilbao-2016","status":"publish","type":"post","link":"https:\/\/bilbao.wordcamp.org\/2016\/siteground-patrocinador-oro-wordcamp-bilbao-2016\/","title":{"rendered":"SiteGround &#8211; Patrocinador Oro de la WordCamp Bilbao 2016"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-1076\" src=\"https:\/\/2016.bilbao.wordcamp.org\/files\/2016\/05\/wordcamp-bilbao-patrocinadores-siteground.png\" alt=\"SiteGround - WordCamp Bilbao\" width=\"488\" height=\"111\" srcset=\"https:\/\/bilbao.wordcamp.org\/2016\/files\/2016\/05\/wordcamp-bilbao-patrocinadores-siteground.png 488w, https:\/\/bilbao.wordcamp.org\/2016\/files\/2016\/05\/wordcamp-bilbao-patrocinadores-siteground-300x68.png 300w\" sizes=\"auto, (max-width: 488px) 100vw, 488px\" \/><\/p>\n<p>Estamos muy contentos de anunciar y dar la bienvenida a SiteGround\u00a0como patrocinador Oro\u00a0de la WordCamp Bilbao 2016.<\/p>\n<p><a title=\"SiteGround\" href=\"http:\/\/www.siteground.com\/\" target=\"_blank\">SiteGround<\/a>, con m\u00e1s de 12 a\u00f1os de experiencia en el sector, proporciona servicios de <a title=\"WordPress Hosting\" href=\"http:\/\/www.siteground.com\/wordpress-hosting.html\" target=\"_blank\">hosting gestionado de WordPress<\/a> de alta calidad y prestaciones. Sus servidores, disponibles en 4 centros de datos en todo el mundo, se han optimizado especialmente para WordPress tanto en velocidad como seguridad, facilitando muchos extras para los fans de WordPress: actualizaciones autom\u00e1ticas para el n\u00facleo WordPress junto con sus plugins, WordPress SuperCacher para aceleraci\u00f3n y velocidad m\u00e1ximas, Stagin, GIT, WP-Cli, Autoinstalador de WordPress para usuarios principiantes, etc&#8230; Todos desarrollados internamente por el equipo de SiteGround. Pero no por ello olvidan la importancia de las buenas caracter\u00edsticas de los alojamientos standard como el registro del nombre del dominio, el servicio de email, panel de control y precios razonables. Tambi\u00e9n disponen de un soporte t\u00e9cnico que no solo est\u00e1 disponible 24\/7 al tel\u00e9fono, chats y ticketing, sino que adem\u00e1s est\u00e1 formado de entusiastas de WordPress que te ayudar\u00e1n con incidencias espec\u00edficas de WordPress.<\/p>\n<p>SiteGround participa activamente involucr\u00e1ndose con la comunidad, hablando, apoyando y asistiendo a multitud de WordCamps por todo el mundo y mediante el patrocinio de eventos WP a lo largo del a\u00f1o. Y quieren contribuir a\u00fan m\u00e1s a la incre\u00edble comunidad de WordPress.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estamos muy contentos de anunciar y dar la bienvenida a SiteGround\u00a0como patrocinador Oro\u00a0de la WordCamp Bilbao 2016. SiteGround, con m\u00e1s de 12 a\u00f1os de experiencia en el sector, proporciona servicios de hosting gestionado de WordPress de alta calidad y prestaciones. &hellip; <a href=\"https:\/\/bilbao.wordcamp.org\/2016\/siteground-patrocinador-oro-wordcamp-bilbao-2016\/\">Sigue leyendo <span class=\"assistive-text\">SiteGround &#8211; Patrocinador Oro de la WordCamp Bilbao 2016<\/span>  <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":13800779,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_crdt_document":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10640],"tags":[],"class_list":["post-1078","post","type-post","status-publish","format-standard","hentry","category-patrocinadores"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pheSAt-ho","_links":{"self":[{"href":"https:\/\/bilbao.wordcamp.org\/2016\/wp-json\/wp\/v2\/posts\/1078","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bilbao.wordcamp.org\/2016\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bilbao.wordcamp.org\/2016\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bilbao.wordcamp.org\/2016\/wp-json\/wp\/v2\/users\/13800779"}],"replies":[{"embeddable":true,"href":"https:\/\/bilbao.wordcamp.org\/2016\/wp-json\/wp\/v2\/comments?post=1078"}],"version-history":[{"count":6,"href":"https:\/\/bilbao.wordcamp.org\/2016\/wp-json\/wp\/v2\/posts\/1078\/revisions"}],"predecessor-version":[{"id":1225,"href":"https:\/\/bilbao.wordcamp.org\/2016\/wp-json\/wp\/v2\/posts\/1078\/revisions\/1225"}],"wp:attachment":[{"href":"https:\/\/bilbao.wordcamp.org\/2016\/wp-json\/wp\/v2\/media?parent=1078"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bilbao.wordcamp.org\/2016\/wp-json\/wp\/v2\/categories?post=1078"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bilbao.wordcamp.org\/2016\/wp-json\/wp\/v2\/tags?post=1078"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}