{"id":1278,"date":"2016-05-25T14:00:06","date_gmt":"2016-05-25T12:00:06","guid":{"rendered":"https:\/\/2016.bilbao.wordcamp.org\/?p=1278"},"modified":"2016-05-25T14:00:45","modified_gmt":"2016-05-25T12:00:45","slug":"ultima-oportunidad-para-conseguir-una-entrada-para-wcbilbao","status":"publish","type":"post","link":"https:\/\/bilbao.wordcamp.org\/2016\/ultima-oportunidad-para-conseguir-una-entrada-para-wcbilbao\/","title":{"rendered":"\u00daltima oportunidad para conseguir una entrada para #WCBilbao"},"content":{"rendered":"<p>Si a\u00fan no tienes tu entrada para la WordCamp Bilbao 2016&#8230; <strong>\u00a1Tenemos buenas noticias!<\/strong><\/p>\n<p>Gracias a nuestros incre\u00edbles patrocinadores, junto con los que presentaremos estos d\u00edas, <strong>podemos sacar a la venta 50 entradas para la #WCBilbao.<\/strong><\/p>\n<p>En el siguiente enlace tienes toda la informaci\u00f3n sobre qu\u00e9 es la WCBilbao y por qu\u00e9 tienes que venir -&gt; <a href=\"https:\/\/2016.bilbao.wordcamp.org\/presentacion-wordcamp-bilbao\/\" target=\"_blank\" rel=\"nofollow\">WordCamp Bilbao 2016<\/a><\/p>\n<p><strong>No esperes ya que el inter\u00e9s es muy alto y se acabar\u00e1n r\u00e1pido<\/strong> (y m\u00e1s ahora a solo 2 semanas del evento) y es muy probable que sea la \u00faltima oportunidad que tendr\u00e1s.<\/p>\n<p style=\"text-align: center\"><a style=\"font-size: 26px\" href=\"https:\/\/2016.bilbao.wordcamp.org\/entradas\/\" rel=\"nofollow\">Hazte con tu entrada ahora<\/a><\/p>\n<p>&nbsp;<\/p>\n<hr \/>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si a\u00fan no tienes tu entrada para la WordCamp Bilbao 2016&#8230; \u00a1Tenemos buenas noticias! Gracias a nuestros incre\u00edbles patrocinadores, junto con los que presentaremos estos d\u00edas, podemos sacar a la venta 50 entradas para la #WCBilbao. En el siguiente enlace &hellip; <a href=\"https:\/\/bilbao.wordcamp.org\/2016\/ultima-oportunidad-para-conseguir-una-entrada-para-wcbilbao\/\">Sigue leyendo <span class=\"assistive-text\">\u00daltima oportunidad para conseguir una entrada para #WCBilbao<\/span>  <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":13800779,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_crdt_document":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[662479],"tags":[],"class_list":["post-1278","post","type-post","status-publish","format-standard","hentry","category-noticias-generales"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pheSAt-kC","_links":{"self":[{"href":"https:\/\/bilbao.wordcamp.org\/2016\/wp-json\/wp\/v2\/posts\/1278","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bilbao.wordcamp.org\/2016\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bilbao.wordcamp.org\/2016\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bilbao.wordcamp.org\/2016\/wp-json\/wp\/v2\/users\/13800779"}],"replies":[{"embeddable":true,"href":"https:\/\/bilbao.wordcamp.org\/2016\/wp-json\/wp\/v2\/comments?post=1278"}],"version-history":[{"count":6,"href":"https:\/\/bilbao.wordcamp.org\/2016\/wp-json\/wp\/v2\/posts\/1278\/revisions"}],"predecessor-version":[{"id":1284,"href":"https:\/\/bilbao.wordcamp.org\/2016\/wp-json\/wp\/v2\/posts\/1278\/revisions\/1284"}],"wp:attachment":[{"href":"https:\/\/bilbao.wordcamp.org\/2016\/wp-json\/wp\/v2\/media?parent=1278"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bilbao.wordcamp.org\/2016\/wp-json\/wp\/v2\/categories?post=1278"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bilbao.wordcamp.org\/2016\/wp-json\/wp\/v2\/tags?post=1278"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}