{"id":841,"date":"2016-04-29T08:32:56","date_gmt":"2016-04-29T06:32:56","guid":{"rendered":"https:\/\/2016.bilbao.wordcamp.org\/?p=841"},"modified":"2016-04-29T12:18:49","modified_gmt":"2016-04-29T10:18:49","slug":"resumen-de-la-semana-6-a-wc","status":"publish","type":"post","link":"https:\/\/bilbao.wordcamp.org\/2016\/resumen-de-la-semana-6-a-wc\/","title":{"rendered":"Resumen de la Semana 6 A.WC."},"content":{"rendered":"<p>Todos aquellos que ya conoc\u00e9is al equipo de organizaci\u00f3n de la <a href=\"http:\/\/www.meetup.com\/es-ES\/WordPress-Bilbao\/\" target=\"_blank\">Comunidad WordPress Bilbao<\/a>, sab\u00e9is que nos gusta ser claros y transparentes con lo que va ocurriendo en la trastienda.<\/p>\n<p>Es por eso que vamos a crear esta serie de art\u00edculos semanales donde iremos contando qu\u00e9 ha ocurrido en esa semana y que esperamos que ocurra en la siguiente.<\/p>\n<p>Esperamos que esto os haga m\u00e1s part\u00edcipes de la WordCamp Bilbao y <strong>os anime tanto a ofrecer vuestra opini\u00f3n e ideas, como a <a href=\"https:\/\/2016.bilbao.wordcamp.org\/entradas\/\" target=\"_blank\" rel=\"nofollow\">comprar vuestra entrada<\/a> y atender este gran evento<\/strong>.<\/p>\n<p><!--more--><\/p>\n<p>Habr\u00e1 cosas que no podemos detallar por falta de confirmaci\u00f3n o \u00a1por que sean sorpresa! pero intentaremos dar los m\u00e1ximos detalles posibles<\/p>\n<p>Este ser\u00e1 el primer resumen a falta de 6 Semanas de la realizaci\u00f3n de la WordCamp Bilbao = 6 Semanas Antes de WordCamp Bilbao.<\/p>\n<h2>Ponentes y Programa<\/h2>\n<p>Ha sido una semana de infarto donde hemos cerrado y presentado a todos los ponentes. Contamos con ponentes de WPBilbao, varios ponentes de WPEspa\u00f1a e incluso ponentes Internacionales que vienen a contarnos su experiencia.<\/p>\n<h3>Detalles y Datos<\/h3>\n<p><strong>Sexo:<br \/>\n<\/strong>Mujeres: 6<br \/>\nHombres: 12<\/p>\n<p>Se ha intentado llegar al 50% pero no se han presentado tantas ponentes. Pero el n\u00famero est\u00e1 muy bien para lo que suele ser la media \u00a1y m\u00e1s en este campo!<\/p>\n<p><strong>Procedencia:<br \/>\n<\/strong>Bilbao y alrededores: 7<br \/>\nSantander: 1<br \/>\nMadrid: 4<br \/>\nSevilla:\u00a02<br \/>\nValencia: 1<br \/>\nInternacional: 3<\/p>\n<p>Contamos con 7 ponentes de Bilbao, 7 de la Comunidad WPEspa\u00f1a y 3 de la Comunidad WPInternacional. No est\u00e1 nada mal el inter\u00e9s generado para ser la primera WordCamp Bilbao. Creemos que son ponentes que pueden aportar y ense\u00f1ar mucho.<\/p>\n<p>El mayor problema ha sido poder encontrar ponentes de la zona, pero esperamos que en siguientes ediciones la cosa cambie y la gente se anime a participar.<\/p>\n<p><strong>Idioma:<\/strong><br \/>\nCastellano: 13<br \/>\nEuskera: 2<br \/>\nIngl\u00e9s: 3<\/p>\n<p>Se realiz\u00f3 una encuesta preguntando qu\u00e9 idiomas se prefer\u00edan para las ponencias. Pod\u00e9is consultar las respuestas de la encuesta en el siguiente enlace: <a href=\"https:\/\/docs.google.com\/spreadsheets\/d\/1Z-WVq3299QtBkO_54alDUZwreERyM9UQOsXDoja47k8\/edit?usp=sharing\" target=\"_blank\">Respuestas Encuesta<\/a>. Agradecer a todas aquellas personas que se respondieron y dieron su opini\u00f3n.<\/p>\n<p>&nbsp;<\/p>\n<h2>Presupuesto<\/h2>\n<p>No nos vamos a enga\u00f1ar, en el presupuesto estamos todav\u00eda muy ajustados. Al ser el primer a\u00f1o no contamos con contactos y apoyos que nos podr\u00edan hacer la realizaci\u00f3n del evento menos \u00abestresante\u00bb.<\/p>\n<p>Por otro lado, hay que <strong>agradecer a todas esas empresas y PERSONAS que nos est\u00e1n apoyando y aportando lo que pueden<\/strong>. Ya que en este aspecto, contamos con muy buenos apoyos que nos facilitan las cosas.<\/p>\n<p>Contamos con varios patrocinios ya cerrados y que presentaremos la semana que viene, junto con algunos patrocinios casi cerrados. Estos patrocinios ayudan a que este evento no lucrativo y de divulgaci\u00f3n pueda realizarse. Si crees que puedes aportar, ya sea como <a href=\"https:\/\/2016.bilbao.wordcamp.org\/patrocina\/\" target=\"_blank\" rel=\"nofollow\">patrocinador<\/a>\u00a0o <a href=\"https:\/\/2016.bilbao.wordcamp.org\/entradas\/\" target=\"_blank\" rel=\"nofollow\">comprando tu entrada<\/a>, no dudes en hacerlo ya que te necesitamos para que todos podamos aprender y mejorar.<\/p>\n<p>Desde la Fundaci\u00f3n se recomienda que el precio de la entrada sea menor a <strong>$20 por CADA d\u00eda de evento<\/strong>. En WCBilbao contamos con un evento de <strong>2 d\u00edas\u00a0por un precio de solo 25 \u20ac.<\/strong><\/p>\n<p>Creemos que es un precio acorde a\u00a0lo que los asistentes pueden obtener. Son 18 ponencias + Networking con gente implicada de su sector + Comida incluida + Sorpresas.<\/p>\n<p>Un detalle importante es que <strong>los ponentes, organizadores y voluntarios no cobran nada<\/strong>. A\u00fan viniendo desde Berlin, como en uno de los casos, no se hace pago alguno ni se costean costes a ninguno de los ponentes. Esto da m\u00e1s valor a lo que implica ser part\u00edcipe de una Comunidad como la de WordPress.<\/p>\n<p>Ten\u00e9is m\u00e1s informaci\u00f3n sobre el presupuesto en la secci\u00f3n de <a href=\"https:\/\/2016.bilbao.wordcamp.org\/wordcamp-bilbao\/transparencia\/\" target=\"_blank\" rel=\"nofollow\">Transparencia<\/a>, incluso acceso a la hoja de presupuesto oficial.<\/p>\n<p>&nbsp;<\/p>\n<h2>Novedades<\/h2>\n<p>En la Comunidad WordPress Bilbao nos encanta hacer cosas algo diferentes y\/o novedosas, como este reporte semanal, y esta vez no iba a ser menos.<\/p>\n<h3>Entradas de Comunidad<\/h3>\n<p>Hemos introducido un Tipo de Entrada que es la Entrada de Comunidad. Con esta entrada lo que haces es permitir que un alumno\/a de un instituto pueda acudir al evento y adentrarse en el mundo de WordPress sin coste alguno.<\/p>\n<p>Se ha vendido una de esas entradas&#8230; pero la idea ha gustado tanto que hay patrocinadores que est\u00e1n patrocinando esas entradas, <strong>\u00a1ya tenemos 5 entradas para 5 alumnos\/as!<\/strong><\/p>\n<p>Si esta idea te gusta y te parece interesante que los j\u00f3venes se adentren en el mundo de WordPress, no dudes en comprar tu Entrada de Patrocinio o en ponerte en <a href=\"https:\/\/2016.bilbao.wordcamp.org\/contacto\/\" target=\"_blank\" rel=\"nofollow\">contacto<\/a> para realizar un patrocinio.<\/p>\n<h3>Networking + Happiness Bar<\/h3>\n<p>Si has visto el <a href=\"https:\/\/2016.bilbao.wordcamp.org\/programa\/\" target=\"_blank\" rel=\"nofollow\">Programa<\/a>, habr\u00e1s comprobado que no hay \u00abPausa para Caf\u00e9\u00bb como tal. No te preocupes, tendremos caf\u00e9, pero este tiempo se enfocar\u00e1 en mejorar el aspecto del networking de los eventos. Queremos incentivar que la gente se conozca y comparta sus experiencias con el resto.<\/p>\n<p>Tambi\u00e9n dispondremos de\u00a0<strong>Happiness Bar<\/strong>. \u00bf\u00bf\u00bfQu\u00e9 es??? El\u00a0Happiness Bar\u00a0es un espacio, en la zona de Networking, donde podr\u00e1s encontrar a varios expertos de diferentes materias y hacerles preguntas y solucionar tus dudas. Contaremos con expertos en Desarrollo de WordPress, Hosting, SEO, Marketing, LOPD, Asesor\u00eda Legal, \u00a1y mucho m\u00e1s!<\/p>\n<hr \/>\n<p>Cualquier sugerencia o duda que teng\u00e1is pod\u00e9is utilizar la secci\u00f3n de comentarios de abajo o poneros en <a href=\"https:\/\/2016.bilbao.wordcamp.org\/contacto\/\" target=\"_blank\" rel=\"nofollow\">contacto<\/a>.<\/p>\n<p>Seguro que podemos mejorar muchas cosas, as\u00ed que no dud\u00e9is en hacernos llegar vuestras ideas.<\/p>\n<p>Aprovecha y compra tu entrada para no perderte nada de todo esto<\/p>\n<p style=\"text-align: center\"><a href=\"https:\/\/2016.bilbao.wordcamp.org\/entradas\/\" target=\"_blank\" rel=\"nofollow\">Comprar Entrada<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Todos aquellos que ya conoc\u00e9is al equipo de organizaci\u00f3n de la Comunidad WordPress Bilbao, sab\u00e9is que nos gusta ser claros y transparentes con lo que va ocurriendo en la trastienda. Es por eso que vamos a crear esta serie de &hellip; <a href=\"https:\/\/bilbao.wordcamp.org\/2016\/resumen-de-la-semana-6-a-wc\/\">Sigue leyendo <span class=\"assistive-text\">Resumen de la Semana 6 A.WC.<\/span>  <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":13800779,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_crdt_document":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[810814],"tags":[811187],"class_list":["post-841","post","type-post","status-publish","format-standard","hentry","category-transparencia","tag-resumen-de-la-semana"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pheSAt-dz","_links":{"self":[{"href":"https:\/\/bilbao.wordcamp.org\/2016\/wp-json\/wp\/v2\/posts\/841","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bilbao.wordcamp.org\/2016\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bilbao.wordcamp.org\/2016\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bilbao.wordcamp.org\/2016\/wp-json\/wp\/v2\/users\/13800779"}],"replies":[{"embeddable":true,"href":"https:\/\/bilbao.wordcamp.org\/2016\/wp-json\/wp\/v2\/comments?post=841"}],"version-history":[{"count":24,"href":"https:\/\/bilbao.wordcamp.org\/2016\/wp-json\/wp\/v2\/posts\/841\/revisions"}],"predecessor-version":[{"id":886,"href":"https:\/\/bilbao.wordcamp.org\/2016\/wp-json\/wp\/v2\/posts\/841\/revisions\/886"}],"wp:attachment":[{"href":"https:\/\/bilbao.wordcamp.org\/2016\/wp-json\/wp\/v2\/media?parent=841"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bilbao.wordcamp.org\/2016\/wp-json\/wp\/v2\/categories?post=841"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bilbao.wordcamp.org\/2016\/wp-json\/wp\/v2\/tags?post=841"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}