{"id":931,"date":"2016-05-17T00:50:37","date_gmt":"2016-05-16T22:50:37","guid":{"rendered":"https:\/\/2016.bilbao.wordcamp.org\/?post_type=wcb_sponsor&#038;p=931"},"modified":"2016-05-17T00:50:37","modified_gmt":"2016-05-16T22:50:37","slug":"arsys","status":"publish","type":"wcb_sponsor","link":"https:\/\/bilbao.wordcamp.org\/2016\/sponsor\/arsys\/","title":{"rendered":"Arsys"},"content":{"rendered":"<p><a title=\"Arsys\" href=\"https:\/\/www.arsys.es\/\" target=\"_blank\" rel=\"nofollow\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-1037\" src=\"https:\/\/2016.bilbao.wordcamp.org\/files\/2016\/05\/wordcamp-bilbao-patrocinadores-arsys.jpg\" alt=\"Arsys - WordCamp Bilbao\" width=\"730\" height=\"328\" srcset=\"https:\/\/bilbao.wordcamp.org\/2016\/files\/2016\/05\/wordcamp-bilbao-patrocinadores-arsys.jpg 730w, https:\/\/bilbao.wordcamp.org\/2016\/files\/2016\/05\/wordcamp-bilbao-patrocinadores-arsys-300x135.jpg 300w, https:\/\/bilbao.wordcamp.org\/2016\/files\/2016\/05\/wordcamp-bilbao-patrocinadores-arsys-500x225.jpg 500w\" sizes=\"auto, (max-width: 730px) 100vw, 730px\" \/><\/a><\/p>\n<p>Estamos muy contentos de anunciar y de <strong>agradecer enormemente a Arsys su patrocinio<\/strong> y ayuda a la realizaci\u00f3n de la <strong>WordCamp Bilbao 2016<\/strong>.<\/p>\n<p><strong>Arsys<\/strong> es el <strong>Proveedor de Servicios Cloud Computing que lidera el mercado espa\u00f1ol de soluciones de Internet para empresas y profesionales IT<\/strong>.\u00a0 Pionero del Cloud Hosting en Europa gracias a su compromiso con la innovaci\u00f3n, Arsys facilita la integraci\u00f3n de las Tecnolog\u00edas de la Informaci\u00f3n en el negocio a trav\u00e9s de una amplia oferta de soluciones de Presencia Web, Cloud Computing, Hosting Gestionado e Infraestructura como Servicio.<\/p>\n<p><strong>Con 266.000 clientes<\/strong>, Arsys es una filial 100% participada por el Grupo United Internet, compa\u00f1\u00eda cotizada con una capitalizaci\u00f3n burs\u00e1til de m\u00e1s de 10.000 millones de euros. Arsys cuenta con una plantilla de m\u00e1s de 300 profesionales y gestiona tres Centros de Datos en Espa\u00f1a y un nodo Cloud en Estados Unidos, en los que est\u00e1n alojadas m\u00e1s de 200.000 p\u00e1ginas web y 1,5 millones de cuentas de correo electr\u00f3nico.<\/p>\n<p>M\u00e1s informaci\u00f3n en\u00a0<a title=\"Arsys\" href=\"http:\/\/www.arsys.es\/\" target=\"_blank\" rel=\"nofollow\">www.arsys.es<\/a>, el blog de Arsys, <a title=\"Twitter Arsys\" href=\"https:\/\/www.twitter.com\/arsys\" target=\"_blank\" rel=\"nofollow\">Twitter<\/a> y en las p\u00e1ginas de Arsys en\u00a0<a href=\"https:\/\/www.facebook.com\/arsys.es\" target=\"_blank\" rel=\"nofollow\">Facebook<\/a>, <a href=\"https:\/\/plus.google.com\/+arsys\" target=\"_blank\" rel=\"nofollow\">Google+<\/a>\u00a0y\u00a0<a href=\"https:\/\/www.linkedin.com\/company\/arsys-internet\" target=\"_blank\" rel=\"nofollow\">LinkedIn<\/a>.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estamos muy contentos de anunciar y de agradecer enormemente a Arsys su patrocinio y ayuda a la realizaci\u00f3n de la WordCamp Bilbao 2016. Arsys es el Proveedor de Servicios Cloud Computing que lidera el mercado espa\u00f1ol de soluciones de Internet &hellip; <a href=\"https:\/\/bilbao.wordcamp.org\/2016\/sponsor\/arsys\/\">Sigue leyendo <span class=\"assistive-text\">Arsys<\/span>  <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"featured_media":0,"template":"","meta":{"_crdt_document":"","_wcpt_sponsor_website":"https:\/\/www.arsys.es\/","footnotes":""},"sponsor_level":[113699],"class_list":["post-931","wcb_sponsor","type-wcb_sponsor","status-publish","hentry","wcb_sponsor_level-patrocinador-platino"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pheSAt-f1","_links":{"self":[{"href":"https:\/\/bilbao.wordcamp.org\/2016\/wp-json\/wp\/v2\/sponsors\/931","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bilbao.wordcamp.org\/2016\/wp-json\/wp\/v2\/sponsors"}],"about":[{"href":"https:\/\/bilbao.wordcamp.org\/2016\/wp-json\/wp\/v2\/types\/wcb_sponsor"}],"version-history":[{"count":2,"href":"https:\/\/bilbao.wordcamp.org\/2016\/wp-json\/wp\/v2\/sponsors\/931\/revisions"}],"predecessor-version":[{"id":1127,"href":"https:\/\/bilbao.wordcamp.org\/2016\/wp-json\/wp\/v2\/sponsors\/931\/revisions\/1127"}],"wp:attachment":[{"href":"https:\/\/bilbao.wordcamp.org\/2016\/wp-json\/wp\/v2\/media?parent=931"}],"wp:term":[{"taxonomy":"wcb_sponsor_level","embeddable":true,"href":"https:\/\/bilbao.wordcamp.org\/2016\/wp-json\/wp\/v2\/sponsor_level?post=931"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}