{"id":210,"date":"2016-11-27T10:00:27","date_gmt":"2016-11-27T09:00:27","guid":{"rendered":"http:\/\/2017.bilbao.wordcamp.org\/?p=210"},"modified":"2016-11-27T16:07:12","modified_gmt":"2016-11-27T15:07:12","slug":"resumen-semana-2","status":"publish","type":"post","link":"https:\/\/bilbao.wordcamp.org\/2017\/resumen-semana-2\/","title":{"rendered":"Resumen Semana #2"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-211\" src=\"http:\/\/2017.bilbao.wordcamp.org\/files\/2016\/11\/resumen-semana-2-wcbilbao-2017.jpg\" alt=\"Resumen Semana 2 - WCBilbao 2017\" width=\"880\" height=\"440\" srcset=\"https:\/\/bilbao.wordcamp.org\/2017\/files\/2016\/11\/resumen-semana-2-wcbilbao-2017.jpg 880w, https:\/\/bilbao.wordcamp.org\/2017\/files\/2016\/11\/resumen-semana-2-wcbilbao-2017-300x150.jpg 300w, https:\/\/bilbao.wordcamp.org\/2017\/files\/2016\/11\/resumen-semana-2-wcbilbao-2017-768x384.jpg 768w, https:\/\/bilbao.wordcamp.org\/2017\/files\/2016\/11\/resumen-semana-2-wcbilbao-2017-500x250.jpg 500w\" sizes=\"auto, (max-width: 880px) 100vw, 880px\" \/><\/p>\n<p>Desde el equipo de Organizaci\u00f3n queremos compartir con toda la comunidad todo lo se lleva a cabo para organizar la WordCamp Bilbao 2017. Es por ello que realizamos res\u00famenes semanales con lo que se ha conseguido y realizado en cada\u00a0equipo.<\/p>\n<p><a title=\"WordCamp Bilbao\" href=\"https:\/\/2017.bilbao.wordcamp.org\/resumen-semana-2\/#castellano\" target=\"_self\">Castellano<\/a> | <a title=\"WordCamp Bilbao\" href=\"https:\/\/2017.bilbao.wordcamp.org\/resumen-semana-2\/#euskera\" target=\"_self\">Euskera<\/a> | <a title=\"WordCamp Bilbao\" href=\"https:\/\/2017.bilbao.wordcamp.org\/resumen-semana-2\/#english\" target=\"_self\">English<\/a><\/p>\n<p><!--more--><\/p>\n<h2>Equipo General<\/h2>\n<p>El \u00abEquipo General\u00bb se encarga de coordinar el resto de equipos, a la par que de pedir presupuestos y gestionar el apartado de las instalaciones del evento.<\/p>\n<p><strong>Tareas Realizadas<\/strong><\/p>\n<ul>\n<li>Conseguir informaci\u00f3n de diferentes opciones de turismo para el viernes del evento<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h2>Equipo de Patrocinadores<\/h2>\n<p>Este equipo se encarga de crear los paquetes de patrocinio, documentaci\u00f3n, contactar y gestionar todo lo relacionado con los patrocinadores.<\/p>\n<p><strong>Tareas Realizadas<\/strong><\/p>\n<ul>\n<li>Preparar lista de posibles patrocinios en especie<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h2>Equipo de Comunicaci\u00f3n<\/h2>\n<p>Este equipo se encarga de idear, redactar y publicar todo lo relacionado con los art\u00edculos y secciones de la web, junto con su publicaci\u00f3n en las redes sociales.<\/p>\n<p><strong>Tareas Realizadas<\/strong><\/p>\n<ul>\n<li>Redactar art\u00edculo Resumen de la Semana<\/li>\n<li>Crear borrador de llamada a patrocinadores<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h2>Equipo de Dise\u00f1o<\/h2>\n<p>El Equipo de Dise\u00f1o se encarga de todo lo relacionado con las im\u00e1genes gr\u00e1ficas para la web, redes sociales, documentaci\u00f3n, etc.<\/p>\n<p><strong>Tareas Realizadas<\/strong><\/p>\n<ul>\n<li>&#8211;<\/li>\n<\/ul>\n<div id=\"euskera\">\n<hr \/>\n<\/div>\n<h2 style=\"text-align: center\">Euskera<\/h2>\n<p>Organizatzaile taldetik zuekin partekatu nai dugu zer egiten dugun guztiak WordCamp Bilbao 2017 aurrera eramateko. Hau dela eta, astero laburpen bat egingo dugo talde bakaoitzak egin duen lan guztiekin.<\/p>\n<h2>Talde Generala<\/h2>\n<p>Talde generala beste taldeak koordinatzen ditu, baita ere aurrekontuak eta kokapena kudeatu behar ditu.<\/p>\n<p><strong>Egindako lana<\/strong><\/p>\n<ul>\n<li>Turismo aukera desberdinak bilatu ekitaldiko ostiralerako<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h2>Babesleen Taldea<\/h2>\n<p>Talde hau babesleen paketeak, dokumentazioa, kontaktatu eta babesleekin dena kudeatu.<\/p>\n<p><strong>Egindako lana<\/strong><\/p>\n<ul>\n<li>Babesle mota desberdinak zerrendatu<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h2>Komunikazio Taldea<\/h2>\n<p>Talde hau web orrialdearen atalak eta albisteak pentsatu, idatzi eta argitaratu behar dute, baita ere sozial median.<\/p>\n<p><strong>Egindako lana<\/strong><\/p>\n<ul>\n<li>Asteko laburpena idatzi<\/li>\n<li>Babesleen deia esteka idatzita utzi<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h2>Diseinu Taldea<\/h2>\n<p>Diseinu taldeak web orrialdearen, social mediaren, dokumentazioaren, eta abarren irudi grafikoak egin behar dute.<\/p>\n<p><strong>Egindako lana<\/strong><\/p>\n<ul>\n<li>&#8211;<\/li>\n<\/ul>\n<div id=\"english\">\n<hr \/>\n<\/div>\n<h2 style=\"text-align: center\">English<\/h2>\n<p>From the organization team we want to share with all the community all the things that we have to do to organize WordCamp Bilbao 2017. That&#8217;s why we are doing week summary where we share all the things that each team has done.<\/p>\n<h2>General Team<\/h2>\n<p>The General Team coordinates the rest of te teams, also asks for budgets and manages all the venue things.<\/p>\n<p><strong>Done Tasks<\/strong><\/p>\n<ul>\n<li>Obtain information for different options of tourism packages for the Friday of the event<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h2>Sponsors Team<\/h2>\n<p>This team creates the sponsors packages, documentation, contacts and manages everything related with sponsors.<\/p>\n<p><strong>Done Tasks<\/strong><\/p>\n<ul>\n<li>Make the different types of sponsors list<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h2>Communication Team<\/h2>\n<p>This team thinks, writes and publishes all the contents and website parts while publishing them in the social media.<\/p>\n<p><strong>Done Tasks<\/strong><\/p>\n<ul>\n<li>Write, publish and share the Week Summary<\/li>\n<li>Write the Call for Sponsors for next week<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h2>Design Team<\/h2>\n<p>This team does all the graphic design for the website, social media, documentation, etc.<\/p>\n<p><strong>Done Tasks<\/strong><\/p>\n<ul>\n<li>&#8211;<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Desde el equipo de Organizaci\u00f3n queremos compartir con toda la comunidad todo lo se lleva a cabo para organizar la WordCamp Bilbao 2017. Es por ello que realizamos res\u00famenes semanales con lo que se ha conseguido y realizado en cada\u00a0equipo. &hellip; <a href=\"https:\/\/bilbao.wordcamp.org\/2017\/resumen-semana-2\/\">Seguir leyendo <span class=\"assistive-text\">Resumen Semana #2<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":13800779,"featured_media":211,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[810814],"tags":[993540],"class_list":["post-210","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-transparencia","tag-resumen-semana"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pheMS7-3o","jetpack_featured_media_url":"https:\/\/bilbao.wordcamp.org\/2017\/files\/2016\/11\/resumen-semana-2-wcbilbao-2017.jpg","_links":{"self":[{"href":"https:\/\/bilbao.wordcamp.org\/2017\/wp-json\/wp\/v2\/posts\/210","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bilbao.wordcamp.org\/2017\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bilbao.wordcamp.org\/2017\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bilbao.wordcamp.org\/2017\/wp-json\/wp\/v2\/users\/13800779"}],"replies":[{"embeddable":true,"href":"https:\/\/bilbao.wordcamp.org\/2017\/wp-json\/wp\/v2\/comments?post=210"}],"version-history":[{"count":7,"href":"https:\/\/bilbao.wordcamp.org\/2017\/wp-json\/wp\/v2\/posts\/210\/revisions"}],"predecessor-version":[{"id":224,"href":"https:\/\/bilbao.wordcamp.org\/2017\/wp-json\/wp\/v2\/posts\/210\/revisions\/224"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bilbao.wordcamp.org\/2017\/wp-json\/wp\/v2\/media\/211"}],"wp:attachment":[{"href":"https:\/\/bilbao.wordcamp.org\/2017\/wp-json\/wp\/v2\/media?parent=210"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bilbao.wordcamp.org\/2017\/wp-json\/wp\/v2\/categories?post=210"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bilbao.wordcamp.org\/2017\/wp-json\/wp\/v2\/tags?post=210"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}