{"id":3642,"date":"2025-04-19T11:46:43","date_gmt":"2025-04-19T09:46:43","guid":{"rendered":"https:\/\/bilbao.wordcamp.org\/2025\/?post_type=wcb_session&#038;p=3642"},"modified":"2025-05-27T18:35:20","modified_gmt":"2025-05-27T16:35:20","slug":"adios-a-los-maquetadores-visuales-o-casi-la-verdad-sobre-el-editor-de-bloques","status":"publish","type":"wcb_session","link":"https:\/\/bilbao.wordcamp.org\/2025\/session\/adios-a-los-maquetadores-visuales-o-casi-la-verdad-sobre-el-editor-de-bloques\/","title":{"rendered":"Adi\u00f3s a los maquetadores visuales (o casi): La verdad sobre el editor de bloques"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Los maquetadores visuales han sido la soluci\u00f3n r\u00e1pida para muchas webs en WordPress, pero \u00bfrealmente los necesitamos en 2025?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con la evoluci\u00f3n del editor de bloques, las excusas para no usarlo se van agotando. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En esta charla, hablaremos de las ventajas (y las trampas) de maquetar con los bloques nativos de WordPress, c\u00f3mo aprovechar theme.json, y por qu\u00e9 no hace falta instalar un maquetador de terceros para hacer una web decente. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Spoiler: igual te toca desaprender algunos malos h\u00e1bitos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los maquetadores visuales han sido la soluci\u00f3n r\u00e1pida para muchas webs en WordPress, pero \u00bfrealmente los necesitamos en 2025? Con la evoluci\u00f3n del editor de bloques, las excusas para no usarlo se van agotando. En esta charla, hablaremos de las ventajas (y las trampas) de maquetar con los bloques nativos de WordPress, c\u00f3mo aprovechar theme.json, [&hellip;]<\/p>\n","protected":false},"author":16828762,"featured_media":0,"template":"","meta":{"_wcpt_session_time":1746886200,"_wcpt_session_duration":1800,"_wcpt_session_type":"session","_wcpt_session_slides":"https:\/\/bilbao.wordcamp.org\/2025\/files\/2025\/05\/Marta-Torre_Adios-a-los-maquetadores-visuales-o-casi-La-verdad-sobre-el-editor-de-bloques.pdf","_wcpt_session_video":"https:\/\/wordpress.tv\/2025\/05\/21\/adios-a-los-maquetadores-visuales-o-casi-la-verdad-sobre-el-editor-de-bloques\/","_wcpt_speaker_id":[3640],"footnotes":""},"session_track":[42],"session_category":[45],"class_list":["post-3642","wcb_session","type-wcb_session","status-publish","hentry","wcb_track-sala-1","wcb_session_category-ponencia"],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pgeeQn-WK","session_date_time":{"date":"10\/05\/2025","time":"16:10"},"session_speakers":[{"id":"3640","slug":"marta-torre","name":"Marta Torre","link":"https:\/\/bilbao.wordcamp.org\/2025\/speaker\/marta-torre\/"}],"session_cats_rendered":"Ponencia","_links":{"self":[{"href":"https:\/\/bilbao.wordcamp.org\/2025\/wp-json\/wp\/v2\/sessions\/3642","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bilbao.wordcamp.org\/2025\/wp-json\/wp\/v2\/sessions"}],"about":[{"href":"https:\/\/bilbao.wordcamp.org\/2025\/wp-json\/wp\/v2\/types\/wcb_session"}],"version-history":[{"count":2,"href":"https:\/\/bilbao.wordcamp.org\/2025\/wp-json\/wp\/v2\/sessions\/3642\/revisions"}],"predecessor-version":[{"id":3644,"href":"https:\/\/bilbao.wordcamp.org\/2025\/wp-json\/wp\/v2\/sessions\/3642\/revisions\/3644"}],"speakers":[{"embeddable":true,"href":"https:\/\/bilbao.wordcamp.org\/2025\/wp-json\/wp\/v2\/speakers\/3640"}],"author":[{"embeddable":true,"href":"https:\/\/bilbao.wordcamp.org\/2025\/wp-json\/wporg\/v1\/users\/martatorre"}],"wp:attachment":[{"href":"https:\/\/bilbao.wordcamp.org\/2025\/wp-json\/wp\/v2\/media?parent=3642"}],"wp:term":[{"taxonomy":"wcb_track","embeddable":true,"href":"https:\/\/bilbao.wordcamp.org\/2025\/wp-json\/wp\/v2\/session_track?post=3642"},{"taxonomy":"wcb_session_category","embeddable":true,"href":"https:\/\/bilbao.wordcamp.org\/2025\/wp-json\/wp\/v2\/session_category?post=3642"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}